{"id":5913,"date":"2024-04-12T12:58:35","date_gmt":"2024-04-12T10:58:35","guid":{"rendered":"https:\/\/inpeak.pl\/produkt\/powercrank-e-single-power-meter-shimano-105-fc-r7100\/"},"modified":"2026-07-15T17:27:32","modified_gmt":"2026-07-15T15:27:32","slug":"powercrank-e-single-misuratore-di-potenza-shimano-105-fc-r7100","status":"publish","type":"product","link":"https:\/\/inpeak.pl\/it\/negozio\/powercrank-e-single-misuratore-di-potenza-shimano-105-fc-r7100\/","title":{"rendered":"POWERCRANK-E Misuratore di potenza | SINGLE | Shimano 105 FC-R7100"},"content":{"rendered":"<p><strong>COS&#8217;\u00c8 IL POWERCRANK-E?<\/strong><\/p>\n<p>\u00c8 la nostra versione pi\u00f9 recente di misuratore di potenza, creata pensando alla modernit\u00e0. Abbiamo dotato l&#8217;affidabile sistema di misurazione POWERCRANK-E di una batteria ricaricabile, che si ricarica con il cavo USB magnetico in dotazione. Non \u00e8 solo un misuratore di potenza, \u00e8 il vostro compagno di allenamento grazie al quale entrerete in un nuovo livello di sportivit\u00e0. Il misuratore di potenza INPEAK POWERCRANK-E utilizza i protocolli di trasmissione ANT+ e BLE per inviare potenza, cadenza e una serie di dati dettagliati sulle prestazioni ciclistiche. L&#8217;alloggiamento a basso profilo, impermeabile e resistente, \u00e8 stato progettato appositamente per le biciclette da strada e da sterrato. Le letture precise e accurate della potenza generata, indipendentemente dalle condizioni atmosferiche, sono garantite dal meccanismo di compensazione automatica della temperatura ATC da -5\u00b0C a +50\u00b0C.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COSA CI RENDE DIVERSI?<\/strong><\/p>\n<ul>\n<li><strong>Creato in Polonia<\/strong> &#8211; siamo noi stessi a firmare questo prodotto,<\/li>\n<li><strong>Prezzo basso<\/strong> &#8211; una delle soluzioni pi\u00f9 economiche sul mercato,<\/li>\n<li><strong>Precisione<\/strong> &#8211; il nostro reparto di Ricerca e Sviluppo non scende a compromessi, ci\u00f2 che conta \u00e8 l&#8217;impeccabilit\u00e0,<\/li>\n<li><strong>Calibrazione individuale<\/strong> &#8211; ogni misura di potenza che installiamo \u00e8 calibrata individualmente,<\/li>\n<li><strong>Compensazione attiva della temperatura<\/strong> &#8211; le variazioni di temperatura non influiscono sulla precisione, la misura si adatta automaticamente,<\/li>\n<li><strong>Durata<\/strong> &#8211; confermata da centinaia di ciclisti professionisti.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div role=\"tabpanel\" aria-labelledby=\"tab-title-description\"><strong>POWERCRANK-E | SINGLE<\/strong><br \/>\nMisuratore di potenza monobraccio integrato nella pedivella <strong>Shimano 105 FC-R7100<\/strong>.<\/div>\n<div role=\"tabpanel\" aria-labelledby=\"tab-title-description\">Progettato senza compromessi per soddisfare le esigenze pi\u00f9 elevate dei ciclisti.<\/div>\n","protected":false},"featured_media":2980,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"cpt_product_category_1":[191],"cpt_product_category_2":[194],"cpt_product_category_3":[195],"product_brand":[],"product_cat":[761],"product_tag":[],"class_list":["post-5913","product","type-product","status-publish","has-post-thumbnail","product_cat-ready-it","product_shipping_class-ready-it","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"acf":[],"_links":{"self":[{"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product\/5913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/comments?post=5913"}],"version-history":[{"count":6,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product\/5913\/revisions"}],"predecessor-version":[{"id":13034,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product\/5913\/revisions\/13034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/media\/2980"}],"wp:attachment":[{"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/media?parent=5913"}],"wp:term":[{"taxonomy":"cpt_product_category_1","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/cpt_product_category_1?post=5913"},{"taxonomy":"cpt_product_category_2","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/cpt_product_category_2?post=5913"},{"taxonomy":"cpt_product_category_3","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/cpt_product_category_3?post=5913"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product_brand?post=5913"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product_cat?post=5913"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/inpeak.pl\/it\/wp-json\/wp\/v2\/product_tag?post=5913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}